{"id":3366,"date":"2021-07-07T07:55:41","date_gmt":"2021-07-07T07:55:41","guid":{"rendered":"https:\/\/materiaisdiversos.com\/?post_type=autores&#038;p=3366"},"modified":"2021-07-07T07:55:41","modified_gmt":"2021-07-07T07:55:41","slug":"alina-folini","status":"publish","type":"autores","link":"https:\/\/materiaisdiversos.com\/en\/autores\/alina-folini\/","title":{"rendered":"Alina Folini"},"content":{"rendered":"<p>Alina Ruiz Folini (Argentina) \u00e9 artista e pesquisadora. O seu trabalho move-se entre a coreografia, a dan\u00e7a e as pr\u00e1ticas curatoriais. Mestre em Pr\u00e1tica C\u00e9nica e Cultura Visual pelo Museu Nacional de Arte UCLM \/ Reina Sof\u00eda 2017-2018. Co-dirige ARQUEOLOGIAS DEL FUTURO \u2013 Festival Internacional de Artes C\u00e9nicas em Buenos Aires. Co-criou o Projeto T\u00c1CTIL com Leticia Scrkycky. \u00c9 bailarina em\u00a0<em>Trilogia Antropof\u00e1gica<\/em>\u00a0e em\u00a0<em>S\u00e9rie Canibal<\/em>\u00a0dirigidas por Tamara Cubas (UY). Vive em Lisboa.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-3366","autores","type-autores","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alina Folini - Materiais Diversos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/materiaisdiversos.com\/autores\/alina-folini\/?lang=en\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alina Folini - Materiais Diversos\" \/>\n<meta property=\"og:description\" content=\"Alina Ruiz Folini (Argentina) \u00e9 artista e pesquisadora. O seu trabalho move-se entre a coreografia, a dan\u00e7a e as pr\u00e1ticas curatoriais. Mestre em Pr\u00e1tica C\u00e9nica e Cultura Visual pelo Museu Nacional de Arte UCLM \/ Reina Sof\u00eda 2017-2018. Co-dirige ARQUEOLOGIAS DEL FUTURO \u2013 Festival Internacional de Artes C\u00e9nicas em Buenos Aires. Co-criou o Projeto T\u00c1CTIL [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/materiaisdiversos.com\/autores\/alina-folini\/?lang=en\" \/>\n<meta property=\"og:site_name\" content=\"Materiais Diversos\" \/>\n<meta property=\"og:image\" content=\"https:\/\/materiaisdiversos.com\/wp-content\/uploads\/materais-diversos-fb.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/materiaisdiversos.com\\\/autores\\\/alina-folini\\\/?lang=en\",\"url\":\"https:\\\/\\\/materiaisdiversos.com\\\/autores\\\/alina-folini\\\/?lang=en\",\"name\":\"Alina Folini - Materiais Diversos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/materiaisdiversos.com\\\/#website\"},\"datePublished\":\"2021-07-07T07:55:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/materiaisdiversos.com\\\/autores\\\/alina-folini\\\/?lang=en#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/materiaisdiversos.com\\\/autores\\\/alina-folini\\\/?lang=en\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/materiaisdiversos.com\\\/autores\\\/alina-folini\\\/?lang=en#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/materiaisdiversos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alina Folini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/materiaisdiversos.com\\\/#website\",\"url\":\"https:\\\/\\\/materiaisdiversos.com\\\/\",\"name\":\"Materiais Diversos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/materiaisdiversos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alina Folini - Materiais Diversos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/materiaisdiversos.com\/autores\/alina-folini\/?lang=en","og_locale":"en_US","og_type":"article","og_title":"Alina Folini - Materiais Diversos","og_description":"Alina Ruiz Folini (Argentina) \u00e9 artista e pesquisadora. O seu trabalho move-se entre a coreografia, a dan\u00e7a e as pr\u00e1ticas curatoriais. Mestre em Pr\u00e1tica C\u00e9nica e Cultura Visual pelo Museu Nacional de Arte UCLM \/ Reina Sof\u00eda 2017-2018. Co-dirige ARQUEOLOGIAS DEL FUTURO \u2013 Festival Internacional de Artes C\u00e9nicas em Buenos Aires. Co-criou o Projeto T\u00c1CTIL [&hellip;]","og_url":"https:\/\/materiaisdiversos.com\/autores\/alina-folini\/?lang=en","og_site_name":"Materiais Diversos","og_image":[{"width":1000,"height":600,"url":"https:\/\/materiaisdiversos.com\/wp-content\/uploads\/materais-diversos-fb.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/materiaisdiversos.com\/autores\/alina-folini\/?lang=en","url":"https:\/\/materiaisdiversos.com\/autores\/alina-folini\/?lang=en","name":"Alina Folini - Materiais Diversos","isPartOf":{"@id":"https:\/\/materiaisdiversos.com\/#website"},"datePublished":"2021-07-07T07:55:41+00:00","breadcrumb":{"@id":"https:\/\/materiaisdiversos.com\/autores\/alina-folini\/?lang=en#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/materiaisdiversos.com\/autores\/alina-folini\/?lang=en"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/materiaisdiversos.com\/autores\/alina-folini\/?lang=en#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/materiaisdiversos.com\/"},{"@type":"ListItem","position":2,"name":"Alina Folini"}]},{"@type":"WebSite","@id":"https:\/\/materiaisdiversos.com\/#website","url":"https:\/\/materiaisdiversos.com\/","name":"Materiais Diversos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/materiaisdiversos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/materiaisdiversos.com\/en\/wp-json\/wp\/v2\/autores-api\/3366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/materiaisdiversos.com\/en\/wp-json\/wp\/v2\/autores-api"}],"about":[{"href":"https:\/\/materiaisdiversos.com\/en\/wp-json\/wp\/v2\/types\/autores"}],"version-history":[{"count":1,"href":"https:\/\/materiaisdiversos.com\/en\/wp-json\/wp\/v2\/autores-api\/3366\/revisions"}],"predecessor-version":[{"id":3367,"href":"https:\/\/materiaisdiversos.com\/en\/wp-json\/wp\/v2\/autores-api\/3366\/revisions\/3367"}],"wp:attachment":[{"href":"https:\/\/materiaisdiversos.com\/en\/wp-json\/wp\/v2\/media?parent=3366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}